{"id":82671,"date":"2026-03-27T13:18:31","date_gmt":"2026-03-27T12:18:31","guid":{"rendered":"https:\/\/www.zennio.com\/es\/?page_id=82671"},"modified":"2026-04-12T12:25:56","modified_gmt":"2026-04-12T10:25:56","slug":"calculadores-lumento","status":"publish","type":"page","link":"https:\/\/www.zennio.com\/es\/calculadores-lumento\/","title":{"rendered":"Calculadores Lumento"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"82671\" class=\"elementor elementor-82671\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-904d34f e-flex e-con-boxed e-con e-parent\" data-id=\"904d34f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f427d9b elementor-widget elementor-widget-heading\" data-id=\"f427d9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Calculadores Lumento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2478522 elementor-widget elementor-widget-text-editor\" data-id=\"2478522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Elija el tipo de l\u00e1mpara \/ tira LED que desea controlar:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1bea1d e-con-full e-flex e-con e-child\" data-id=\"d1bea1d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-834d377 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"834d377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/lumento\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">L\u00e1mpara\/tira LED de corriente constante<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb3c817 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bb3c817\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/lumento-calculos-x\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">L\u00e1mpara\/tira LED de tensi\u00f3n constante<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Calculadores Lumento Elija el tipo de l\u00e1mpara \/ tira LED que desea controlar: L\u00e1mpara\/tira LED de corriente constante L\u00e1mpara\/tira LED de tensi\u00f3n constante<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-82671","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calculadores Lumento - Zennio<\/title>\n<meta name=\"description\" content=\"Calculadores Lumento Elija el tipo de l\u00e1mpara \/ tira LED que desea controlar: L\u00e1mpara\/tira LED de corriente constante L\u00e1mpara\/tira LED de tensi\u00f3n\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calculadores Lumento - Zennio\" \/>\n<meta property=\"og:description\" content=\"Calculadores Lumento Elija el tipo de l\u00e1mpara \/ tira LED que desea controlar: L\u00e1mpara\/tira LED de corriente constante L\u00e1mpara\/tira LED de tensi\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zennio.com\/es\/calculadores-lumento\/\" \/>\n<meta property=\"og:site_name\" content=\"Zennio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZennioSpain\/?locale=es_ES\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-12T10:25:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zennio.com\/wp-content\/uploads\/2026\/04\/ISOTIPO_en.png\" \/>\n\t<meta property=\"og:image:width\" content=\"906\" \/>\n\t<meta property=\"og:image:height\" content=\"906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/calculadores-lumento\\\/\",\"url\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/calculadores-lumento\\\/\",\"name\":\"Calculadores Lumento - Zennio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/#website\"},\"datePublished\":\"2026-03-27T12:18:31+00:00\",\"dateModified\":\"2026-04-12T10:25:56+00:00\",\"description\":\"Calculadores Lumento Elija el tipo de l\u00e1mpara \\\/ tira LED que desea controlar: L\u00e1mpara\\\/tira LED de corriente constante L\u00e1mpara\\\/tira LED de tensi\u00f3n\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zennio.com\\\/es\\\/calculadores-lumento\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/\",\"name\":\"Zennio\",\"description\":\"Soluciones de tecnolog\u00eda para hoteles, viviendas y edificios.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/#organization\"},\"alternateName\":\"Zennio Global\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/#organization\",\"name\":\"Zennio\",\"alternateName\":\"Zennio\",\"url\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zennio.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ISOTIPO_en.png\",\"contentUrl\":\"https:\\\/\\\/www.zennio.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ISOTIPO_en.png\",\"width\":906,\"height\":906,\"caption\":\"Zennio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zennio.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZennioSpain\\\/?locale=es_ES\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calculadores Lumento - Zennio","description":"Calculadores Lumento Elija el tipo de l\u00e1mpara \/ tira LED que desea controlar: L\u00e1mpara\/tira LED de corriente constante L\u00e1mpara\/tira LED de tensi\u00f3n","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Calculadores Lumento - Zennio","og_description":"Calculadores Lumento Elija el tipo de l\u00e1mpara \/ tira LED que desea controlar: L\u00e1mpara\/tira LED de corriente constante L\u00e1mpara\/tira LED de tensi\u00f3n","og_url":"https:\/\/www.zennio.com\/es\/calculadores-lumento\/","og_site_name":"Zennio","article_publisher":"https:\/\/www.facebook.com\/ZennioSpain\/?locale=es_ES","article_modified_time":"2026-04-12T10:25:56+00:00","og_image":[{"width":906,"height":906,"url":"https:\/\/www.zennio.com\/wp-content\/uploads\/2026\/04\/ISOTIPO_en.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zennio.com\/es\/calculadores-lumento\/","url":"https:\/\/www.zennio.com\/es\/calculadores-lumento\/","name":"Calculadores Lumento - Zennio","isPartOf":{"@id":"https:\/\/www.zennio.com\/es\/#website"},"datePublished":"2026-03-27T12:18:31+00:00","dateModified":"2026-04-12T10:25:56+00:00","description":"Calculadores Lumento Elija el tipo de l\u00e1mpara \/ tira LED que desea controlar: L\u00e1mpara\/tira LED de corriente constante L\u00e1mpara\/tira LED de tensi\u00f3n","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zennio.com\/es\/calculadores-lumento\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.zennio.com\/es\/#website","url":"https:\/\/www.zennio.com\/es\/","name":"Zennio","description":"Soluciones de tecnolog\u00eda para hoteles, viviendas y edificios.","publisher":{"@id":"https:\/\/www.zennio.com\/es\/#organization"},"alternateName":"Zennio Global","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zennio.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.zennio.com\/es\/#organization","name":"Zennio","alternateName":"Zennio","url":"https:\/\/www.zennio.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zennio.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.zennio.com\/wp-content\/uploads\/2026\/04\/ISOTIPO_en.png","contentUrl":"https:\/\/www.zennio.com\/wp-content\/uploads\/2026\/04\/ISOTIPO_en.png","width":906,"height":906,"caption":"Zennio"},"image":{"@id":"https:\/\/www.zennio.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZennioSpain\/?locale=es_ES"]}]}},"_links":{"self":[{"href":"https:\/\/www.zennio.com\/es\/wp-json\/wp\/v2\/pages\/82671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zennio.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zennio.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zennio.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zennio.com\/es\/wp-json\/wp\/v2\/comments?post=82671"}],"version-history":[{"count":0,"href":"https:\/\/www.zennio.com\/es\/wp-json\/wp\/v2\/pages\/82671\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zennio.com\/es\/wp-json\/wp\/v2\/media?parent=82671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}